{"id":756,"date":"2021-11-13T10:43:57","date_gmt":"2021-11-13T10:43:57","guid":{"rendered":"https:\/\/stara.glovis.ba\/?post_type=product&#038;p=756"},"modified":"2022-01-09T18:48:47","modified_gmt":"2022-01-09T18:48:47","slug":"kula-kmd-2200","status":"publish","type":"product","link":"https:\/\/stara.glovis.ba\/sv\/proizvod\/kula-kmd-2200\/","title":{"rendered":"Kula KMD-2200"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 mpc-column\" data-column-id=\"mpc_column-726a56f8dcb548c\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_tta-container\" data-vc-action=\"collapse\"><div class=\"vc_general vc_tta vc_tta-tabs vc_tta-color-grey vc_tta-style-total vc_tta-shape-rounded vc_tta-spacing-1 vc_tta-tabs-position-top vc_tta-controls-align-center\"><div class=\"vc_tta-tabs-container\"><ul class=\"vc_tta-tabs-list\"><li class=\"vc_tta-tab vc_active\" data-vc-tab><a href=\"#tehnicki-opis\" data-vc-tabs data-vc-container=\".vc_tta\"><span class=\"vc_tta-title-text\">Tehni&#269;ki opis<\/span><\/a><\/li><li class=\"vc_tta-tab\" data-vc-tab><a href=\"#1635336437626-337dcafd-c429\" data-vc-tabs data-vc-container=\".vc_tta\"><span class=\"vc_tta-title-text\">Detalji<\/span><\/a><\/li><li class=\"vc_tta-tab\" data-vc-tab><a href=\"#1635338034048-fba91162-900d\" data-vc-tabs data-vc-container=\".vc_tta\"><span class=\"vc_tta-title-text\">Download<\/span><\/a><\/li><\/ul><\/div><div class=\"vc_tta-panels-container\"><div class=\"vc_tta-panels\"><div class=\"vc_tta-panel vc_active\" id=\"tehnicki-opis\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#tehnicki-opis\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Tehni&#269;ki opis<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\"><div id=\"topis\" class=\"vc_row wpb_row vc_inner vc_row-fluid no-bottom-margins mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-xs-6 mpc-column\" data-column-id=\"mpc_column-996a56f8dcb1abc\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Uzrast djece<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 mpc-column\" data-column-id=\"mpc_column-196a56f8dcb1de3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;text-align:right;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>3 &ndash; 14<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div id=\"topis\" class=\"vc_row wpb_row vc_inner vc_row-fluid no-bottom-margins mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-xs-6 mpc-column\" data-column-id=\"mpc_column-446a56f8dcb229d\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Du&#382;ina \/ &scaron;irina \/ visina<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 mpc-column\" data-column-id=\"mpc_column-956a56f8dcb2577\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;text-align:right;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>5&times;3,5&times;3,4 m<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div id=\"topis\" class=\"vc_row wpb_row vc_inner vc_row-fluid no-bottom-margins mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-xs-6 mpc-column\" data-column-id=\"mpc_column-276a56f8dcb2a23\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Kriti&#269;na visina pada<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 mpc-column\" data-column-id=\"mpc_column-856a56f8dcb2d04\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;text-align:right;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>1,5 m<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div id=\"topis\" class=\"vc_row wpb_row vc_inner vc_row-fluid no-bottom-margins mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-xs-6 mpc-column\" data-column-id=\"mpc_column-766a56f8dcb317c\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Povr&scaron;ina<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 mpc-column\" data-column-id=\"mpc_column-686a56f8dcb3466\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;text-align:right;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>37,8 m<sup>2<\/sup><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_tta-panel\" id=\"1635336437626-337dcafd-c429\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#1635336437626-337dcafd-c429\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Detalji<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_  wpex-lightbox\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"https:\/\/stara.glovis.ba\/wp-content\/uploads\/2021\/10\/Sigurnosna-zona.jpg\" target=\"_self\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/stara.glovis.ba\/wp-content\/uploads\/2021\/10\/Sigurnosna-zona.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" srcset=\"https:\/\/stara.glovis.ba\/wp-content\/uploads\/2021\/10\/Sigurnosna-zona.jpg 800w, https:\/\/stara.glovis.ba\/wp-content\/uploads\/2021\/10\/Sigurnosna-zona-300x300.jpg 300w, https:\/\/stara.glovis.ba\/wp-content\/uploads\/2021\/10\/Sigurnosna-zona-150x150.jpg 150w, https:\/\/stara.glovis.ba\/wp-content\/uploads\/2021\/10\/Sigurnosna-zona-768x768.jpg 768w, https:\/\/stara.glovis.ba\/wp-content\/uploads\/2021\/10\/Sigurnosna-zona-600x600.jpg 600w, https:\/\/stara.glovis.ba\/wp-content\/uploads\/2021\/10\/Sigurnosna-zona-100x100.jpg 100w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\"><\/a>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vcex-module vcex-divider vcex-divider-solid wpex-my-0 vcex-divider-center wpex-float-center wpex-max-w-100 wpex-mx-auto wpex-block wpex-h-0 wpex-border-b wpex-border-solid wpex-border-gray-200\" style=\"width:100%;border-bottom-width:1px;border-color:#848484;\"><\/div><\/div><\/div><div class=\"vc_tta-panel\" id=\"1635338034048-fba91162-900d\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#1635338034048-fba91162-900d\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Download<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\"><div class=\"vcex-module vcex-divider vcex-divider-solid wpex-my-0 vcex-divider-center wpex-float-center wpex-max-w-100 wpex-mx-auto wpex-block wpex-h-0 wpex-border-b wpex-border-solid wpex-border-gray-200\" style=\"width:100%;border-bottom-width:1px;border-color:#848484;\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"Tehni&#269;ki opisDetaljiDownloadTehni&#269;ki opis Uzrast djece 3 - 14 Du&#382;ina \/ &scaron;irina \/ visina 5x3,5x3,4 m Kriti&#269;na visina pada 1,5 m Povr&scaron;ina 37,8 m2 Detalji Download","protected":false},"featured_media":757,"template":"","meta":[],"product_cat":[20,18],"product_tag":[],"class_list":["post-756","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-woody-ecco","product_cat-glovisplay","entry","has-media"],"_links":{"self":[{"href":"https:\/\/stara.glovis.ba\/sv\/wp-json\/wp\/v2\/product\/756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stara.glovis.ba\/sv\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/stara.glovis.ba\/sv\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stara.glovis.ba\/sv\/wp-json\/wp\/v2\/media\/757"}],"wp:attachment":[{"href":"https:\/\/stara.glovis.ba\/sv\/wp-json\/wp\/v2\/media?parent=756"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/stara.glovis.ba\/sv\/wp-json\/wp\/v2\/product_cat?post=756"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/stara.glovis.ba\/sv\/wp-json\/wp\/v2\/product_tag?post=756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}