{"id":1335,"date":"2021-12-11T08:13:01","date_gmt":"2021-12-11T08:13:01","guid":{"rendered":"https:\/\/stara.glovis.ba\/?post_type=product&#038;p=1335"},"modified":"2022-01-11T12:07:31","modified_gmt":"2022-01-11T12:07:31","slug":"dvogled-l","status":"publish","type":"product","link":"https:\/\/stara.glovis.ba\/sv\/proizvod\/dvogled-l\/","title":{"rendered":"Dvogled L"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 mpc-column\" data-column-id=\"mpc_column-966a5711a6c8f91\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_tta-container\" data-vc-action=\"collapse\"><div class=\"vc_general vc_tta vc_tta-tabs vc_tta-color-grey vc_tta-style-total vc_tta-shape-rounded vc_tta-spacing-1 vc_tta-tabs-position-top vc_tta-controls-align-center\"><div class=\"vc_tta-tabs-container\"><ul class=\"vc_tta-tabs-list\"><li class=\"vc_tta-tab vc_active\" data-vc-tab><a href=\"#tehnicki-opis\" data-vc-tabs data-vc-container=\".vc_tta\"><span class=\"vc_tta-title-text\">Tehni&#269;ki opis<\/span><\/a><\/li><li class=\"vc_tta-tab\" data-vc-tab><a href=\"#1635336437626-337dcafd-c429\" data-vc-tabs data-vc-container=\".vc_tta\"><span class=\"vc_tta-title-text\">Detalji<\/span><\/a><\/li><li class=\"vc_tta-tab\" data-vc-tab><a href=\"#1635338034048-fba91162-900d\" data-vc-tabs data-vc-container=\".vc_tta\"><span class=\"vc_tta-title-text\">Download<\/span><\/a><\/li><\/ul><\/div><div class=\"vc_tta-panels-container\"><div class=\"vc_tta-panels\"><div class=\"vc_tta-panel vc_active\" id=\"tehnicki-opis\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#tehnicki-opis\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Tehni&#269;ki opis<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\"><div class=\"vcex-module vcex-divider vcex-divider-solid wpex-my-0 vcex-divider-center wpex-float-center wpex-max-w-100 wpex-mx-auto wpex-block wpex-h-0 wpex-border-b wpex-border-solid wpex-border-gray-200\" style=\"width:100%;border-bottom-width:1px;border-color:#848484;\"><\/div><\/div><\/div><div class=\"vc_tta-panel\" id=\"1635336437626-337dcafd-c429\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#1635336437626-337dcafd-c429\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Detalji<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\"><div class=\"vcex-module vcex-divider vcex-divider-solid wpex-my-0 vcex-divider-center wpex-float-center wpex-max-w-100 wpex-mx-auto wpex-block wpex-h-0 wpex-border-b wpex-border-solid wpex-border-gray-200\" style=\"width:100%;border-bottom-width:1px;border-color:#848484;\"><\/div><\/div><\/div><div class=\"vc_tta-panel\" id=\"1635338034048-fba91162-900d\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#1635338034048-fba91162-900d\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Download<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\"><div class=\"vcex-module vcex-divider vcex-divider-solid wpex-my-0 vcex-divider-center wpex-float-center wpex-max-w-100 wpex-mx-auto wpex-block wpex-h-0 wpex-border-b wpex-border-solid wpex-border-gray-200\" style=\"width:100%;border-bottom-width:1px;border-color:#848484;\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"Tehni&#269;ki opisDetaljiDownloadTehni&#269;ki opisDetaljiDownload","protected":false},"featured_media":1336,"template":"","meta":[],"product_cat":[43,40],"product_tag":[],"class_list":["post-1335","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-dodaci","product_cat-plavi-zeko","entry","has-media"],"_links":{"self":[{"href":"https:\/\/stara.glovis.ba\/sv\/wp-json\/wp\/v2\/product\/1335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stara.glovis.ba\/sv\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/stara.glovis.ba\/sv\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stara.glovis.ba\/sv\/wp-json\/wp\/v2\/media\/1336"}],"wp:attachment":[{"href":"https:\/\/stara.glovis.ba\/sv\/wp-json\/wp\/v2\/media?parent=1335"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/stara.glovis.ba\/sv\/wp-json\/wp\/v2\/product_cat?post=1335"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/stara.glovis.ba\/sv\/wp-json\/wp\/v2\/product_tag?post=1335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}