{"id":779,"date":"2021-11-13T16:58:21","date_gmt":"2021-11-13T16:58:21","guid":{"rendered":"https:\/\/stara.glovis.ba\/?post_type=product&#038;p=779"},"modified":"2023-08-22T19:29:16","modified_gmt":"2023-08-22T19:29:16","slug":"rb-0011","status":"publish","type":"product","link":"https:\/\/stara.glovis.ba\/en\/proizvod\/rb-0011\/","title":{"rendered":"RB-0011"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 mpc-column\" data-column-id=\"mpc_column-266a56f8d2882fe\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_tta-container\" data-vc-action=\"collapse\"><div class=\"vc_general vc_tta vc_tta-tabs vc_tta-color-grey vc_tta-style-total vc_tta-shape-rounded vc_tta-spacing-1 vc_tta-tabs-position-top vc_tta-controls-align-center\"><div class=\"vc_tta-tabs-container\"><ul class=\"vc_tta-tabs-list\"><li class=\"vc_tta-tab vc_active\" data-vc-tab><a href=\"#tehnicki-opis\" data-vc-tabs data-vc-container=\".vc_tta\"><span class=\"vc_tta-title-text\">Tehni&#269;ki opis<\/span><\/a><\/li><li class=\"vc_tta-tab\" data-vc-tab><a href=\"#1635336437626-337dcafd-c429\" data-vc-tabs data-vc-container=\".vc_tta\"><span class=\"vc_tta-title-text\">Detalji<\/span><\/a><\/li><li class=\"vc_tta-tab\" data-vc-tab><a href=\"#1635338034048-fba91162-900d\" data-vc-tabs data-vc-container=\".vc_tta\"><span class=\"vc_tta-title-text\">Download<\/span><\/a><\/li><\/ul><\/div><div class=\"vc_tta-panels-container\"><div class=\"vc_tta-panels\"><div class=\"vc_tta-panel vc_active\" id=\"tehnicki-opis\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#tehnicki-opis\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Tehni&#269;ki opis<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\"><div id=\"topis\" class=\"vc_row wpb_row vc_inner vc_row-fluid no-bottom-margins mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-xs-6 mpc-column\" data-column-id=\"mpc_column-276a56f8d28530d\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Uzrast djece<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 mpc-column\" data-column-id=\"mpc_column-686a56f8d285655\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;text-align:right;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>2+<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div id=\"topis\" class=\"vc_row wpb_row vc_inner vc_row-fluid no-bottom-margins mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-xs-6 mpc-column\" data-column-id=\"mpc_column-576a56f8d285aec\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Du&#382;ina \/ &scaron;irina \/ visina<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 mpc-column\" data-column-id=\"mpc_column-466a56f8d285c42\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><div id=\"topis\" class=\"vc_row wpb_row vc_inner vc_row-fluid no-bottom-margins mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-xs-6 mpc-column\" data-column-id=\"mpc_column-526a56f8d286092\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Kriti&#269;na visina pada<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 mpc-column\" data-column-id=\"mpc_column-386a56f8d28635d\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;text-align:right;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>0,9 m<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div id=\"topis\" class=\"vc_row wpb_row vc_inner vc_row-fluid no-bottom-margins mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-xs-6 mpc-column\" data-column-id=\"mpc_column-96a56f8d2867d0\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Povr&scaron;ina<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 mpc-column\" data-column-id=\"mpc_column-626a56f8d286aa0\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;text-align:right;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>43,9 m<sup>2<\/sup><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_tta-panel\" id=\"1635336437626-337dcafd-c429\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#1635336437626-337dcafd-c429\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Detalji<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_  wpex-lightbox\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"https:\/\/stara.glovis.ba\/wp-content\/uploads\/2021\/10\/Sigurnosna-zona.jpg\" target=\"_self\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"617\" height=\"505\" src=\"https:\/\/stara.glovis.ba\/wp-content\/uploads\/2021\/11\/RB-0011-B.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" srcset=\"https:\/\/stara.glovis.ba\/wp-content\/uploads\/2021\/11\/RB-0011-B.jpg 617w, https:\/\/stara.glovis.ba\/wp-content\/uploads\/2021\/11\/RB-0011-B-300x246.jpg 300w, https:\/\/stara.glovis.ba\/wp-content\/uploads\/2021\/11\/RB-0011-B-600x491.jpg 600w\" sizes=\"auto, (max-width: 617px) 100vw, 617px\"><\/a>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vcex-module vcex-divider vcex-divider-solid wpex-my-0 vcex-divider-center wpex-float-center wpex-max-w-100 wpex-mx-auto wpex-block wpex-h-0 wpex-border-b wpex-border-solid wpex-border-gray-200\" style=\"width:100%;border-bottom-width:1px;border-color:#848484;\"><\/div><\/div><\/div><div class=\"vc_tta-panel\" id=\"1635338034048-fba91162-900d\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#1635338034048-fba91162-900d\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Download<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\"><div class=\"vcex-module vcex-divider vcex-divider-solid wpex-my-0 vcex-divider-center wpex-float-center wpex-max-w-100 wpex-mx-auto wpex-block wpex-h-0 wpex-border-b wpex-border-solid wpex-border-gray-200\" style=\"width:100%;border-bottom-width:1px;border-color:#848484;\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"Tehni&#269;ki opisDetaljiDownloadTehni&#269;ki opis Uzrast djece 2+ Du&#382;ina \/ &scaron;irina \/ visina Kriti&#269;na visina pada 0,9 m Povr&scaron;ina 43,9 m2 Detalji Download","protected":false},"featured_media":2080,"template":"","meta":[],"product_cat":[22,18],"product_tag":[],"class_list":["post-779","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-robinia","product_cat-glovisplay","entry","has-media"],"_links":{"self":[{"href":"https:\/\/stara.glovis.ba\/en\/wp-json\/wp\/v2\/product\/779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stara.glovis.ba\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/stara.glovis.ba\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stara.glovis.ba\/en\/wp-json\/wp\/v2\/media\/2080"}],"wp:attachment":[{"href":"https:\/\/stara.glovis.ba\/en\/wp-json\/wp\/v2\/media?parent=779"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/stara.glovis.ba\/en\/wp-json\/wp\/v2\/product_cat?post=779"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/stara.glovis.ba\/en\/wp-json\/wp\/v2\/product_tag?post=779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}