{"id":763,"date":"2021-11-13T11:04:36","date_gmt":"2021-11-13T11:04:36","guid":{"rendered":"https:\/\/stara.glovis.ba\/?post_type=product&#038;p=763"},"modified":"2022-01-09T18:48:47","modified_gmt":"2022-01-09T18:48:47","slug":"kula-kmd-2203","status":"publish","type":"product","link":"https:\/\/stara.glovis.ba\/en\/proizvod\/kula-kmd-2203\/","title":{"rendered":"Kula KMD-2203"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 mpc-column\" data-column-id=\"mpc_column-816a57118ff257d\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_tta-container\" data-vc-action=\"collapse\"><div class=\"vc_general vc_tta vc_tta-tabs vc_tta-color-grey vc_tta-style-total vc_tta-shape-rounded vc_tta-spacing-1 vc_tta-tabs-position-top vc_tta-controls-align-center\"><div class=\"vc_tta-tabs-container\"><ul class=\"vc_tta-tabs-list\"><li class=\"vc_tta-tab vc_active\" data-vc-tab><a href=\"#tehnicki-opis\" data-vc-tabs data-vc-container=\".vc_tta\"><span class=\"vc_tta-title-text\">Tehni&#269;ki opis<\/span><\/a><\/li><li class=\"vc_tta-tab\" data-vc-tab><a href=\"#1635336437626-337dcafd-c429\" data-vc-tabs data-vc-container=\".vc_tta\"><span class=\"vc_tta-title-text\">Detalji<\/span><\/a><\/li><li class=\"vc_tta-tab\" data-vc-tab><a href=\"#1635338034048-fba91162-900d\" data-vc-tabs data-vc-container=\".vc_tta\"><span class=\"vc_tta-title-text\">Download<\/span><\/a><\/li><\/ul><\/div><div class=\"vc_tta-panels-container\"><div class=\"vc_tta-panels\"><div class=\"vc_tta-panel vc_active\" id=\"tehnicki-opis\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#tehnicki-opis\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Tehni&#269;ki opis<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\"><div id=\"topis\" class=\"vc_row wpb_row vc_inner vc_row-fluid no-bottom-margins mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-xs-6 mpc-column\" data-column-id=\"mpc_column-346a57118fefed2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Uzrast djece<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 mpc-column\" data-column-id=\"mpc_column-96a57118ff0207\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;text-align:right;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>1 &ndash; 8<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div id=\"topis\" class=\"vc_row wpb_row vc_inner vc_row-fluid no-bottom-margins mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-xs-6 mpc-column\" data-column-id=\"mpc_column-566a57118ff06ff\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Du&#382;ina \/ &scaron;irina \/ visina<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 mpc-column\" data-column-id=\"mpc_column-276a57118ff09ef\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;text-align:right;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>2,9&times;3,6&times;2,6 m<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div id=\"topis\" class=\"vc_row wpb_row vc_inner vc_row-fluid no-bottom-margins mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-xs-6 mpc-column\" data-column-id=\"mpc_column-526a57118ff0eba\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Kriti&#269;na visina pada<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 mpc-column\" data-column-id=\"mpc_column-516a57118ff11ae\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;text-align:right;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>0,9 m<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div id=\"topis\" class=\"vc_row wpb_row vc_inner vc_row-fluid no-bottom-margins mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-xs-6 mpc-column\" data-column-id=\"mpc_column-566a57118ff1683\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Povr&scaron;ina<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 mpc-column\" data-column-id=\"mpc_column-896a57118ff1961\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;text-align:right;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>32 m<sup>2<\/sup><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_tta-panel\" id=\"1635336437626-337dcafd-c429\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#1635336437626-337dcafd-c429\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Detalji<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\"><div class=\"vcex-module vcex-divider vcex-divider-solid wpex-my-0 vcex-divider-center wpex-float-center wpex-max-w-100 wpex-mx-auto wpex-block wpex-h-0 wpex-border-b wpex-border-solid wpex-border-gray-200\" style=\"width:100%;border-bottom-width:1px;border-color:#848484;\"><\/div><\/div><\/div><div class=\"vc_tta-panel\" id=\"1635338034048-fba91162-900d\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#1635338034048-fba91162-900d\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Download<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\"><div class=\"vcex-module vcex-divider vcex-divider-solid wpex-my-0 vcex-divider-center wpex-float-center wpex-max-w-100 wpex-mx-auto wpex-block wpex-h-0 wpex-border-b wpex-border-solid wpex-border-gray-200\" style=\"width:100%;border-bottom-width:1px;border-color:#848484;\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"Tehni&#269;ki opisDetaljiDownloadTehni&#269;ki opis Uzrast djece 1 - 8 Du&#382;ina \/ &scaron;irina \/ visina 2,9x3,6x2,6 m Kriti&#269;na visina pada 0,9 m Povr&scaron;ina 32 m2 DetaljiDownload","protected":false},"featured_media":764,"template":"","meta":[],"product_cat":[20,18],"product_tag":[],"class_list":["post-763","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-woody-ecco","product_cat-glovisplay","entry","has-media"],"_links":{"self":[{"href":"https:\/\/stara.glovis.ba\/en\/wp-json\/wp\/v2\/product\/763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stara.glovis.ba\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/stara.glovis.ba\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stara.glovis.ba\/en\/wp-json\/wp\/v2\/media\/764"}],"wp:attachment":[{"href":"https:\/\/stara.glovis.ba\/en\/wp-json\/wp\/v2\/media?parent=763"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/stara.glovis.ba\/en\/wp-json\/wp\/v2\/product_cat?post=763"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/stara.glovis.ba\/en\/wp-json\/wp\/v2\/product_tag?post=763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}