{"id":2090,"date":"2023-08-22T19:48:50","date_gmt":"2023-08-22T19:48:50","guid":{"rendered":"https:\/\/stara.glovis.ba\/?post_type=product&#038;p=2090"},"modified":"2023-08-22T19:50:03","modified_gmt":"2023-08-22T19:50:03","slug":"rb-0146","status":"publish","type":"product","link":"https:\/\/stara.glovis.ba\/de\/proizvod\/rb-0146\/","title":{"rendered":"RB-0146"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 mpc-column\" data-column-id=\"mpc_column-616a56f8c18127e\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_tta-container\" data-vc-action=\"collapse\"><div class=\"vc_general vc_tta vc_tta-tabs vc_tta-color-grey vc_tta-style-total vc_tta-shape-rounded vc_tta-spacing-1 vc_tta-tabs-position-top vc_tta-controls-align-center\"><div class=\"vc_tta-tabs-container\"><ul class=\"vc_tta-tabs-list\"><li class=\"vc_tta-tab vc_active\" data-vc-tab><a href=\"#tehnicki-opis\" data-vc-tabs data-vc-container=\".vc_tta\"><span class=\"vc_tta-title-text\">Tehni&#269;ki opis<\/span><\/a><\/li><li class=\"vc_tta-tab\" data-vc-tab><a href=\"#1635336437626-337dcafd-c429\" data-vc-tabs data-vc-container=\".vc_tta\"><span class=\"vc_tta-title-text\">Detalji<\/span><\/a><\/li><li class=\"vc_tta-tab\" data-vc-tab><a href=\"#1635338034048-fba91162-900d\" data-vc-tabs data-vc-container=\".vc_tta\"><span class=\"vc_tta-title-text\">Download<\/span><\/a><\/li><\/ul><\/div><div class=\"vc_tta-panels-container\"><div class=\"vc_tta-panels\"><div class=\"vc_tta-panel vc_active\" id=\"tehnicki-opis\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#tehnicki-opis\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Tehni&#269;ki opis<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\"><div id=\"topis\" class=\"vc_row wpb_row vc_inner vc_row-fluid no-bottom-margins mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-xs-6 mpc-column\" data-column-id=\"mpc_column-776a56f8c17df08\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Uzrast djece<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 mpc-column\" data-column-id=\"mpc_column-316a56f8c17e245\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;text-align:right;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>5+<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div id=\"topis\" class=\"vc_row wpb_row vc_inner vc_row-fluid no-bottom-margins mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-xs-6 mpc-column\" data-column-id=\"mpc_column-1006a56f8c17e714\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Du&#382;ina \/ &scaron;irina \/ visina<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 mpc-column\" data-column-id=\"mpc_column-346a56f8c17e854\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><div id=\"topis\" class=\"vc_row wpb_row vc_inner vc_row-fluid no-bottom-margins mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-xs-6 mpc-column\" data-column-id=\"mpc_column-46a56f8c17ecc8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Kriti&#269;na visina pada<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 mpc-column\" data-column-id=\"mpc_column-406a56f8c17efbb\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;text-align:right;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>2,4 m<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div id=\"topis\" class=\"vc_row wpb_row vc_inner vc_row-fluid no-bottom-margins mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-xs-6 mpc-column\" data-column-id=\"mpc_column-826a56f8c17f473\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Povr&scaron;ina<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 mpc-column\" data-column-id=\"mpc_column-276a56f8c17f755\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"font-family:Nunito;font-size:18px;text-align:right;\" class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>83,7 m<sup>2<\/sup><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_tta-panel\" id=\"1635336437626-337dcafd-c429\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#1635336437626-337dcafd-c429\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Detalji<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_  wpex-lightbox\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"https:\/\/stara.glovis.ba\/wp-content\/uploads\/2021\/10\/Sigurnosna-zona.jpg\" target=\"_self\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"538\" src=\"https:\/\/stara.glovis.ba\/wp-content\/uploads\/2021\/11\/RB-0015-B.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" srcset=\"https:\/\/stara.glovis.ba\/wp-content\/uploads\/2021\/11\/RB-0015-B.jpg 600w, https:\/\/stara.glovis.ba\/wp-content\/uploads\/2021\/11\/RB-0015-B-300x269.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\"><\/a>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"vcex-module vcex-divider vcex-divider-solid wpex-my-0 vcex-divider-center wpex-float-center wpex-max-w-100 wpex-mx-auto wpex-block wpex-h-0 wpex-border-b wpex-border-solid wpex-border-gray-200\" style=\"width:100%;border-bottom-width:1px;border-color:#848484;\"><\/div><\/div><\/div><div class=\"vc_tta-panel\" id=\"1635338034048-fba91162-900d\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#1635338034048-fba91162-900d\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Download<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\"><div class=\"vcex-module vcex-divider vcex-divider-solid wpex-my-0 vcex-divider-center wpex-float-center wpex-max-w-100 wpex-mx-auto wpex-block wpex-h-0 wpex-border-b wpex-border-solid wpex-border-gray-200\" style=\"width:100%;border-bottom-width:1px;border-color:#848484;\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"Tehni&#269;ki opisDetaljiDownloadTehni&#269;ki opis Uzrast djece 5+ Du&#382;ina \/ &scaron;irina \/ visina Kriti&#269;na visina pada 2,4 m Povr&scaron;ina 83,7 m2 Detalji Download","protected":false},"featured_media":2091,"template":"","meta":[],"product_cat":[22,18],"product_tag":[],"class_list":["post-2090","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-robinia","product_cat-glovisplay","entry","has-media"],"_links":{"self":[{"href":"https:\/\/stara.glovis.ba\/de\/wp-json\/wp\/v2\/product\/2090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stara.glovis.ba\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/stara.glovis.ba\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stara.glovis.ba\/de\/wp-json\/wp\/v2\/media\/2091"}],"wp:attachment":[{"href":"https:\/\/stara.glovis.ba\/de\/wp-json\/wp\/v2\/media?parent=2090"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/stara.glovis.ba\/de\/wp-json\/wp\/v2\/product_cat?post=2090"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/stara.glovis.ba\/de\/wp-json\/wp\/v2\/product_tag?post=2090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}